{"id":115,"count":3,"description":"","link":"https:\/\/hobijam.co.id\/blog\/tag\/rolex\/","name":"rolex","slug":"rolex","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>rolex Archives - Blog | HOBIJAM Indonesia<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"rolex Archives - Blog | HOBIJAM Indonesia\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hobijam.co.id\/blog\/tag\/rolex\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog | HOBIJAM Indonesia\" \/>\n<meta property=\"og:image\" content=\"https:\/\/hobijam.co.id\/blog\/wp-content\/uploads\/2024\/01\/1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/hobijam.co.id\/blog\/tag\/rolex\/\",\"url\":\"https:\/\/hobijam.co.id\/blog\/tag\/rolex\/\",\"name\":\"rolex Archives - Blog | HOBIJAM Indonesia\",\"isPartOf\":{\"@id\":\"https:\/\/hobijam.co.id\/blog\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/hobijam.co.id\/blog\/tag\/rolex\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/hobijam.co.id\/blog\/tag\/rolex\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/hobijam.co.id\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"rolex\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/hobijam.co.id\/blog\/#website\",\"url\":\"https:\/\/hobijam.co.id\/blog\/\",\"name\":\"Blog | HOBIJAM Indonesia\",\"description\":\"Hobijam provides a wide range of watch brands with the best quality and prices. Our team is always available 24\/7 to assist you in the buying and selling process. We also offer a service center for watch maintenance. Hobijam guarantees the quality of the watches sold with a 100% money-back guarantee if they don\u2019t meet the initial agreement. Please contact us now to have the best experience in purchasing your dream watch.\",\"publisher\":{\"@id\":\"https:\/\/hobijam.co.id\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/hobijam.co.id\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/hobijam.co.id\/blog\/#organization\",\"name\":\"HOBIJAM Indonesia\",\"url\":\"https:\/\/hobijam.co.id\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/hobijam.co.id\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/hobijam.co.id\/blog\/wp-content\/uploads\/2023\/11\/LOGO-1-1.png\",\"contentUrl\":\"https:\/\/hobijam.co.id\/blog\/wp-content\/uploads\/2023\/11\/LOGO-1-1.png\",\"width\":512,\"height\":222,\"caption\":\"HOBIJAM Indonesia\"},\"image\":{\"@id\":\"https:\/\/hobijam.co.id\/blog\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"rolex Archives - Blog | HOBIJAM Indonesia","robots":{"index":"noindex","follow":"follow"},"og_locale":"en_US","og_type":"article","og_title":"rolex Archives - Blog | HOBIJAM Indonesia","og_url":"https:\/\/hobijam.co.id\/blog\/tag\/rolex\/","og_site_name":"Blog | HOBIJAM Indonesia","og_image":[{"width":1080,"height":1080,"url":"https:\/\/hobijam.co.id\/blog\/wp-content\/uploads\/2024\/01\/1.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/hobijam.co.id\/blog\/tag\/rolex\/","url":"https:\/\/hobijam.co.id\/blog\/tag\/rolex\/","name":"rolex Archives - Blog | HOBIJAM Indonesia","isPartOf":{"@id":"https:\/\/hobijam.co.id\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/hobijam.co.id\/blog\/tag\/rolex\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/hobijam.co.id\/blog\/tag\/rolex\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/hobijam.co.id\/blog\/"},{"@type":"ListItem","position":2,"name":"rolex"}]},{"@type":"WebSite","@id":"https:\/\/hobijam.co.id\/blog\/#website","url":"https:\/\/hobijam.co.id\/blog\/","name":"Blog | HOBIJAM Indonesia","description":"Hobijam provides a wide range of watch brands with the best quality and prices. Our team is always available 24\/7 to assist you in the buying and selling process. We also offer a service center for watch maintenance. Hobijam guarantees the quality of the watches sold with a 100% money-back guarantee if they don\u2019t meet the initial agreement. Please contact us now to have the best experience in purchasing your dream watch.","publisher":{"@id":"https:\/\/hobijam.co.id\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hobijam.co.id\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/hobijam.co.id\/blog\/#organization","name":"HOBIJAM Indonesia","url":"https:\/\/hobijam.co.id\/blog\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/hobijam.co.id\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/hobijam.co.id\/blog\/wp-content\/uploads\/2023\/11\/LOGO-1-1.png","contentUrl":"https:\/\/hobijam.co.id\/blog\/wp-content\/uploads\/2023\/11\/LOGO-1-1.png","width":512,"height":222,"caption":"HOBIJAM Indonesia"},"image":{"@id":"https:\/\/hobijam.co.id\/blog\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/hobijam.co.id\/blog\/wp-json\/wp\/v2\/tags\/115"}],"collection":[{"href":"https:\/\/hobijam.co.id\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/hobijam.co.id\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/hobijam.co.id\/blog\/wp-json\/wp\/v2\/posts?tags=115"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}